{"id":26826,"date":"2026-08-31T14:25:07","date_gmt":"2026-08-31T14:25:07","guid":{"rendered":"https:\/\/logisth.ai\/xion-at-the-wien-energie-business-run-2026\/"},"modified":"2026-09-01T09:11:10","modified_gmt":"2026-09-01T09:11:10","slug":"xion-at-the-wien-energie-business-run-2026","status":"publish","type":"post","link":"https:\/\/logisth.ai\/en\/xion-at-the-wien-energie-business-run-2026\/","title":{"rendered":"Xion at the Wien Energie Business Run 2026"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"26826\" class=\"elementor elementor-26826 elementor-26753\">\n\t\t\t\t<div class=\"elementor-element elementor-element-293e5ce e-con-full thegem-e-con-layout-thegem e-flex e-con e-parent\" data-id=\"293e5ce\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;thegem_container_layout&quot;:&quot;thegem&quot;}\">\r\n\t\t<div class=\"elementor-element elementor-element-bb4360a e-con-full thegem-e-con-layout-thegem e-flex e-con e-child\" data-id=\"bb4360a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;thegem_container_layout&quot;:&quot;thegem&quot;}\">\r\n\t\t\t\t<div class=\"elementor-element elementor-element-b7210a8 flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-thegem-animated-heading\" data-id=\"b7210a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"thegem-animated-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"thegem-heading thegem-animated-heading title-h2\" id=\"thegem-heading-b7210a8\"><span class=\"colored elementor-repeater-item-6d59b7d\" style=\"color: #020101;\">Let&#039;s meet at Booth 58 in the VIP Center!<\/span> <\/h1><style type=\"text\/css\">#thegem-heading-b7210a8 {margin: 0;}<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-370a110 flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-thegem-icon\" data-id=\"370a110\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;thegem_elementor_preset&quot;:&quot;circle&quot;}\" data-widget_type=\"thegem-icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"centered-box icon-inline-position\">\n\n\t\t\t\t<a role=\"button\" aria-label=\"Read more\">\n\n\t\t\t\t<div class=\"gem-icon gem-icon-pack-fontawesome gem-icon-size-small  gem-icon-shape-circle \">\n\n\t\t\t\t\n\t\t\t\t<div class=\"gem-icon-inner\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"padding-box-inner\">\n\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t<span class=\"gem-icon-half-1\"><span class=\"back-angle\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"gem-mdi mdi-checkbox-blank-circle\"><\/i>\t\t\t\t\t<\/span><\/span>\n\t\t\t\t\t<span class=\"gem-icon-half-2\"><span class=\"back-angle\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"gem-mdi mdi-checkbox-blank-circle\"><\/i>\t\t\t\t\t<\/span><\/span>\n\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8d8f5b6 e-con-full thegem-e-con-layout-thegem e-flex e-con e-child\" data-id=\"8d8f5b6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;thegem_container_layout&quot;:&quot;thegem&quot;}\">\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-51e9ed4 e-con-full thegem-e-con-layout-thegem e-flex e-con e-parent\" data-id=\"51e9ed4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;thegem_container_layout&quot;:&quot;thegem&quot;}\">\r\n\t\t\t\t<div class=\"elementor-element elementor-element-beff914 elementor-widget__width-initial elementor-widget-mobile__width-inherit flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-text-editor\" data-id=\"beff914\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\r\n\t\t\t\t\t\t<p class=\"isSelectedEnd\"><strong>Running together. Networking together.<\/strong> <a href=\"http:\/\/www.xion.t\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Xion<\/a> will once again be part of the Wien Energie Business Run on Vienna&#8217;s Donauinsel in 2026. On <strong>September 10, 2026<\/strong>, athletic teams, companies, customers, and partners will come together for exercise, team spirit, and personal encounters. <\/p>\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8bd248 elementor-widget__width-initial elementor-widget-mobile__width-inherit flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-text-editor\" data-id=\"a8bd248\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\r\n\t\t\t\t\t\t<h3 class=\"isSelectedEnd\">Visit us at <strong>Booth 58<\/strong> and let&#8217;s wrap up the evening together.<\/h3>\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-551f498 e-con-full thegem-e-con-layout-thegem e-flex e-con e-parent\" data-id=\"551f498\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;thegem_container_layout&quot;:&quot;thegem&quot;}\">\r\n\t\t<div class=\"elementor-element elementor-element-f82e050 e-con-full thegem-e-con-layout-thegem e-flex e-con e-child\" data-id=\"f82e050\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;thegem_container_layout&quot;:&quot;thegem&quot;}\">\r\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74802f9 flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-thegem-icon\" data-id=\"74802f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;thegem_elementor_preset&quot;:&quot;circle&quot;}\" data-widget_type=\"thegem-icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"centered-box icon-inline-position\">\n\n\t\t\t\t<a role=\"button\" aria-label=\"Read more\">\n\n\t\t\t\t<div class=\"gem-icon gem-icon-pack-fontawesome gem-icon-size-small  gem-icon-shape-circle \">\n\n\t\t\t\t\n\t\t\t\t<div class=\"gem-icon-inner\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"padding-box-inner\">\n\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t<span class=\"gem-icon-half-1\"><span class=\"back-angle\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"gem-mdi mdi-checkbox-blank-circle\"><\/i>\t\t\t\t\t<\/span><\/span>\n\t\t\t\t\t<span class=\"gem-icon-half-2\"><span class=\"back-angle\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"gem-mdi mdi-checkbox-blank-circle\"><\/i>\t\t\t\t\t<\/span><\/span>\n\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a628945 e-con-full thegem-e-con-layout-thegem e-flex e-con e-child\" data-id=\"a628945\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;thegem_container_layout&quot;:&quot;thegem&quot;}\">\r\n\t\t\t\t<div class=\"elementor-element elementor-element-29dce2e flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-thegem-animated-heading\" data-id=\"29dce2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"thegem-animated-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"thegem-heading thegem-animated-heading title-h3\" id=\"thegem-heading-29dce2e\"><span class=\"colored elementor-repeater-item-6d59b7d\" style=\"color: #020101;\">More than just a running event<\/span> <\/h2><style type=\"text\/css\">#thegem-heading-29dce2e {margin: 0;}<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8b8475d e-con-full thegem-e-con-layout-thegem e-flex e-con e-parent\" data-id=\"8b8475d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;thegem_container_layout&quot;:&quot;thegem&quot;}\">\r\n\t\t\t\t<div class=\"elementor-element elementor-element-f1b1f4b elementor-widget__width-initial elementor-widget-mobile__width-inherit flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-text-editor\" data-id=\"f1b1f4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\r\n\t\t\t\t\t\t<p class=\"isSelectedEnd\">The Wien Energie Business Run stands for motivation, solidarity, and shared experiences. Colleagues start as a team, cheer each other on, and celebrate crossing the finish line together. <\/p>\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b660f0 elementor-widget__width-initial elementor-widget-mobile__width-inherit flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-text-editor\" data-id=\"8b660f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\r\n\t\t\t\t\t\t<p class=\"isSelectedEnd\">This team spirit also shapes our daily work at <a href=\"http:\/\/www.xion.at\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Xion<\/a>: together, we create great solutions, strong partnerships, and new perspectives. That is why the Business Run is much more than a sporting competition for us. It provides the ideal setting to see familiar faces again, make new contacts, and exchange ideas personally away from the daily work routine.  <\/p>\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b1a908b e-con-full thegem-e-con-layout-thegem e-flex e-con e-parent\" data-id=\"b1a908b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;thegem_container_layout&quot;:&quot;thegem&quot;}\">\r\n\t\t<div class=\"elementor-element elementor-element-da3d47f e-con-full thegem-e-con-layout-thegem e-flex e-con e-child\" data-id=\"da3d47f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;thegem_container_layout&quot;:&quot;thegem&quot;}\">\r\n\t\t\t\t<div class=\"elementor-element elementor-element-e5216db flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-thegem-animated-heading\" data-id=\"e5216db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"thegem-animated-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"thegem-heading thegem-animated-heading title-h3\" id=\"thegem-heading-e5216db\"><span class=\"colored elementor-repeater-item-6d59b7d\" style=\"color: #020101;\">Visit Xion at Booth 58 in the VIP Center<\/span> <\/h2><style type=\"text\/css\">#thegem-heading-e5216db {margin: 0;}<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-de401b0 flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-thegem-icon\" data-id=\"de401b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;thegem_elementor_preset&quot;:&quot;circle&quot;}\" data-widget_type=\"thegem-icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"centered-box icon-inline-position\">\n\n\t\t\t\t<a role=\"button\" aria-label=\"Read more\">\n\n\t\t\t\t<div class=\"gem-icon gem-icon-pack-fontawesome gem-icon-size-small  gem-icon-shape-circle \">\n\n\t\t\t\t\n\t\t\t\t<div class=\"gem-icon-inner\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"padding-box-inner\">\n\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t<span class=\"gem-icon-half-1\"><span class=\"back-angle\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"gem-mdi mdi-checkbox-blank-circle\"><\/i>\t\t\t\t\t<\/span><\/span>\n\t\t\t\t\t<span class=\"gem-icon-half-2\"><span class=\"back-angle\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"gem-mdi mdi-checkbox-blank-circle\"><\/i>\t\t\t\t\t<\/span><\/span>\n\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e519f17 e-con-full thegem-e-con-layout-thegem e-flex e-con e-child\" data-id=\"e519f17\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;thegem_container_layout&quot;:&quot;thegem&quot;}\">\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-81af84d e-con-full thegem-e-con-layout-thegem e-flex e-con e-parent\" data-id=\"81af84d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;thegem_container_layout&quot;:&quot;thegem&quot;}\">\r\n\t\t\t\t<div class=\"elementor-element elementor-element-6228862 elementor-widget__width-initial elementor-widget-mobile__width-inherit flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-text-editor\" data-id=\"6228862\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\r\n\t\t\t\t\t\t<h4 class=\"isSelectedEnd\"><a href=\"http:\/\/www.xion.at\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Xion<\/a> will be represented with its own booth at the Wien Energie Business Run 2026. You can find us at <strong>Booth 58 in the VIP Center<\/strong>. <\/h4>\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5923b05 elementor-widget__width-initial elementor-widget-mobile__width-inherit flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-text-editor\" data-id=\"5923b05\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\r\n\t\t\t\t\t\t<p class=\"isSelectedEnd\">Whether you are participating in the run yourself, accompanying your team, or using the evening for networking: stop by and get to know our team personally. We look forward to good conversations, exciting encounters, and exchanging ideas with customers, partners, and interested parties. <\/p>\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8d51914 e-con-full thegem-e-con-layout-thegem e-flex e-con e-parent\" data-id=\"8d51914\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;thegem_container_layout&quot;:&quot;thegem&quot;}\">\r\n\t\t<div class=\"elementor-element elementor-element-4c299fe e-con-full thegem-e-con-layout-thegem e-flex e-con e-child\" data-id=\"4c299fe\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;thegem_container_layout&quot;:&quot;thegem&quot;}\">\r\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73851ba flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-thegem-icon\" data-id=\"73851ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;thegem_elementor_preset&quot;:&quot;circle&quot;}\" data-widget_type=\"thegem-icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"centered-box icon-inline-position\">\n\n\t\t\t\t<a role=\"button\" aria-label=\"Read more\">\n\n\t\t\t\t<div class=\"gem-icon gem-icon-pack-fontawesome gem-icon-size-small  gem-icon-shape-circle \">\n\n\t\t\t\t\n\t\t\t\t<div class=\"gem-icon-inner\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"padding-box-inner\">\n\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t<span class=\"gem-icon-half-1\"><span class=\"back-angle\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"gem-mdi mdi-checkbox-blank-circle\"><\/i>\t\t\t\t\t<\/span><\/span>\n\t\t\t\t\t<span class=\"gem-icon-half-2\"><span class=\"back-angle\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"gem-mdi mdi-checkbox-blank-circle\"><\/i>\t\t\t\t\t<\/span><\/span>\n\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0d3b624 e-con-full thegem-e-con-layout-thegem e-flex e-con e-child\" data-id=\"0d3b624\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;thegem_container_layout&quot;:&quot;thegem&quot;}\">\r\n\t\t\t\t<div class=\"elementor-element elementor-element-d1344bb elementor-widget__width-initial flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-thegem-animated-heading\" data-id=\"d1344bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"thegem-animated-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"thegem-heading thegem-animated-heading title-h2\" id=\"thegem-heading-d1344bb\"><span class=\"colored elementor-repeater-item-6d59b7d\" style=\"color: #020101;\">After-Run Drink and Networking<\/span> <\/h1><style type=\"text\/css\">#thegem-heading-d1344bb {margin: 0;}<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e814fd5 e-con-full thegem-e-con-layout-thegem e-flex e-con e-parent\" data-id=\"e814fd5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;thegem_container_layout&quot;:&quot;thegem&quot;}\">\r\n\t\t\t\t<div class=\"elementor-element elementor-element-86b33b5 elementor-widget__width-initial elementor-widget-mobile__width-inherit flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-text-editor\" data-id=\"86b33b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\r\n\t\t\t\t\t\t<h4 class=\"isSelectedEnd\">After the run, we cordially invite you to an <strong>after-run drink at our Booth 58<\/strong>.<\/h4>\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5417395 elementor-widget__width-initial elementor-widget-mobile__width-inherit flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-text-editor\" data-id=\"5417395\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\r\n\t\t\t\t\t\t<p class=\"isSelectedEnd\">Join us in toasting a successful finish, soak in the athletic atmosphere, and take the opportunity for relaxed networking. The best conversations often happen over a cold drink. <\/p>\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7a00b47 e-con-full thegem-e-con-layout-thegem e-flex e-con e-parent\" data-id=\"7a00b47\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;thegem_container_layout&quot;:&quot;thegem&quot;}\">\r\n\t\t<div class=\"elementor-element elementor-element-3d91c18 e-con-full thegem-e-con-layout-thegem e-flex e-con e-child\" data-id=\"3d91c18\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;thegem_container_layout&quot;:&quot;thegem&quot;}\">\r\n\t\t\t\t<div class=\"elementor-element elementor-element-223b321 flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-thegem-animated-heading\" data-id=\"223b321\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"thegem-animated-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"thegem-heading thegem-animated-heading title-h3\" id=\"thegem-heading-223b321\"><span class=\"colored elementor-repeater-item-6d59b7d\" style=\"color: #020101;\">Wien Energie Business Run 2026: All Information at a Glance<\/span> <\/h2><style type=\"text\/css\">#thegem-heading-223b321 {margin: 0;}<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29c887d flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-thegem-icon\" data-id=\"29c887d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;thegem_elementor_preset&quot;:&quot;circle&quot;}\" data-widget_type=\"thegem-icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"centered-box icon-inline-position\">\n\n\t\t\t\t<a role=\"button\" aria-label=\"Read more\">\n\n\t\t\t\t<div class=\"gem-icon gem-icon-pack-fontawesome gem-icon-size-small  gem-icon-shape-circle \">\n\n\t\t\t\t\n\t\t\t\t<div class=\"gem-icon-inner\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"padding-box-inner\">\n\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t<span class=\"gem-icon-half-1\"><span class=\"back-angle\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"gem-mdi mdi-checkbox-blank-circle\"><\/i>\t\t\t\t\t<\/span><\/span>\n\t\t\t\t\t<span class=\"gem-icon-half-2\"><span class=\"back-angle\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"gem-mdi mdi-checkbox-blank-circle\"><\/i>\t\t\t\t\t<\/span><\/span>\n\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b5b6389 e-con-full thegem-e-con-layout-thegem e-flex e-con e-child\" data-id=\"b5b6389\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;thegem_container_layout&quot;:&quot;thegem&quot;}\">\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-90d2288 e-con-full thegem-e-con-layout-thegem e-flex e-con e-parent\" data-id=\"90d2288\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;thegem_container_layout&quot;:&quot;thegem&quot;}\">\r\n\t\t\t\t<div class=\"elementor-element elementor-element-355fe6a elementor-widget__width-initial elementor-widget-mobile__width-inherit flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-text-editor\" data-id=\"355fe6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\r\n\t\t\t\t\t\t<ul><li><strong>Event:<\/strong> Wien Energie Business Run 2026<\/li><li><strong>Date:<\/strong> Thursday, September 10, 2026<\/li><li><strong>Location:<\/strong> Vienna Donauinsel<\/li><li><strong>Xion Booth:<\/strong> VIP Center | Booth 58<\/li><li><strong>Highlight:<\/strong> After-run drink and networking from 3:30 PM<\/li><\/ul>\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c7433d6 e-con-full thegem-e-con-layout-thegem e-flex e-con e-parent\" data-id=\"c7433d6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;thegem_container_layout&quot;:&quot;thegem&quot;}\">\r\n\t\t<div class=\"elementor-element elementor-element-6b08e6c e-con-full thegem-e-con-layout-thegem e-flex e-con e-child\" data-id=\"6b08e6c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;thegem_container_layout&quot;:&quot;thegem&quot;}\">\r\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-600b4af flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-thegem-icon\" data-id=\"600b4af\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;thegem_elementor_preset&quot;:&quot;circle&quot;}\" data-widget_type=\"thegem-icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"centered-box icon-inline-position\">\n\n\t\t\t\t<a role=\"button\" aria-label=\"Read more\">\n\n\t\t\t\t<div class=\"gem-icon gem-icon-pack-fontawesome gem-icon-size-small  gem-icon-shape-circle \">\n\n\t\t\t\t\n\t\t\t\t<div class=\"gem-icon-inner\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"padding-box-inner\">\n\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t<span class=\"gem-icon-half-1\"><span class=\"back-angle\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"gem-mdi mdi-checkbox-blank-circle\"><\/i>\t\t\t\t\t<\/span><\/span>\n\t\t\t\t\t<span class=\"gem-icon-half-2\"><span class=\"back-angle\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"gem-mdi mdi-checkbox-blank-circle\"><\/i>\t\t\t\t\t<\/span><\/span>\n\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-12af378 e-con-full thegem-e-con-layout-thegem e-flex e-con e-child\" data-id=\"12af378\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;thegem_container_layout&quot;:&quot;thegem&quot;}\">\r\n\t\t\t\t<div class=\"elementor-element elementor-element-47bccde elementor-widget__width-initial flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-thegem-animated-heading\" data-id=\"47bccde\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"thegem-animated-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"thegem-heading thegem-animated-heading title-h3\" id=\"thegem-heading-47bccde\"><span class=\"colored elementor-repeater-item-6d59b7d\" style=\"color: #020101;\">Reaching the goal together<\/span> <\/h6><style type=\"text\/css\">#thegem-heading-47bccde {margin: 0;}<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-29d4482 e-con-full thegem-e-con-layout-thegem e-flex e-con e-parent\" data-id=\"29d4482\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;thegem_container_layout&quot;:&quot;thegem&quot;}\">\r\n\t\t\t\t<div class=\"elementor-element elementor-element-e8bed30 elementor-widget__width-initial elementor-widget-mobile__width-inherit flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-text-editor\" data-id=\"e8bed30\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\r\n\t\t\t\t\t\t<p class=\"isSelectedEnd\">We look forward to being part of the Wien Energie Business Run again in 2026 \u2013 as a team, as a company, and as a host at <strong>Booth 58 in the VIP Center<\/strong>.<\/p>\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a5df882 elementor-widget__width-initial elementor-widget-mobile__width-inherit flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-text-editor\" data-id=\"a5df882\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\r\n\t\t\t\t\t\t<h4 class=\"isSelectedEnd\">Visit <a href=\"http:\/\/www.xion.at\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Xion<\/a> at Booth 58. We look forward to a sporting and social evening with you!<\/h4><p><strong>Your XION Team<\/strong><\/p>\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Xion will be at the Wien Energie Business Run on September 10, 2026. Visit us at Booth 58 for an after-run drink and networking. <\/p>\n","protected":false},"author":2,"featured_media":26822,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[90,29],"tags":[],"class_list":["post-26826","post","type-post","status-publish","format-standard","has-post-thumbnail","category-product-news-2","category-worth-knowing"],"menu_order":0,"_links":{"self":[{"href":"https:\/\/logisth.ai\/en\/wp-json\/wp\/v2\/posts\/26826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/logisth.ai\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/logisth.ai\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/logisth.ai\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/logisth.ai\/en\/wp-json\/wp\/v2\/comments?post=26826"}],"version-history":[{"count":1,"href":"https:\/\/logisth.ai\/en\/wp-json\/wp\/v2\/posts\/26826\/revisions"}],"predecessor-version":[{"id":26835,"href":"https:\/\/logisth.ai\/en\/wp-json\/wp\/v2\/posts\/26826\/revisions\/26835"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/logisth.ai\/en\/wp-json\/wp\/v2\/media\/26822"}],"wp:attachment":[{"href":"https:\/\/logisth.ai\/en\/wp-json\/wp\/v2\/media?parent=26826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/logisth.ai\/en\/wp-json\/wp\/v2\/categories?post=26826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/logisth.ai\/en\/wp-json\/wp\/v2\/tags?post=26826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}